{"id":2745,"date":"2019-02-21T09:11:48","date_gmt":"2019-02-21T08:11:48","guid":{"rendered":"https:\/\/agencepoush-newmatriciel.pf503.wpserveur.net\/?p=2745"},"modified":"2019-02-21T09:11:48","modified_gmt":"2019-02-21T08:11:48","slug":"le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre","status":"publish","type":"post","link":"https:\/\/www.matriciel.be\/en\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/","title":{"rendered":"Le chantier de la nouvelle salle de sport Terre-Neuve \u00e0 Bruxelles d\u00e9marre !"},"content":{"rendered":"<p><strong>Informations g\u00e9n\u00e9rales<\/strong><\/p>\n<p><strong>Programme :\u00a0<\/strong>Construction d&#8217;une salle de sport en int\u00e9rieur d\u2019\u00eelot<br \/>\n<strong>Situation :\u00a0<\/strong>Angle Rue Terre Neuve et Rue Roger Van Der Weyden \u00e0 Bruxelles<br \/>\n<strong>Surface : <\/strong>2.584\u00a0m<sup>2<\/sup><br \/>\n<strong>Ma\u00eetre de l\u2019Ouvrage :\u00a0<\/strong>Ville de Bruxelles<br \/>\n<strong>Architecte :\u00a0<\/strong>MDW Architecture<br \/>\n<strong>Dates :\u00a0<\/strong>laur\u00e9at concours en septembre 2016 &#8211; d\u00e9but chantier en f\u00e9vrier 2018<\/p>\n<p><strong>Description du projet<\/strong><\/p>\n<p>Le hall sportif est \u00e9tabli dans un contexte particulier\u00a0: sur une parcelle enclav\u00e9e, elle int\u00e8gre deux murs mitoyens. L\u2019architecture est ainsi largement vitr\u00e9es sur les fa\u00e7ades sud-est et sud-ouest du b\u00e2timent afin d\u2019apporter un maximum d\u2019\u00e9clairage naturel dans les dojos et la grande salle multi-sport et de b\u00e9n\u00e9ficier d\u2019apports solaires gratuits en hiver et en mi-saison.<\/p>\n<p>En parall\u00e8le, des mesures sont mises en place pour assurer le confort d\u2019\u00e9t\u00e9 et \u00e9viter les surchauffes.<\/p>\n<p>Enfin, pour r\u00e9duire les consommations en \u00e9nergie primaire du b\u00e2timent, une attention particuli\u00e8re est apport\u00e9e \u00e0 l\u2019\u00e9clairage artificiel, ainsi qu\u2019\u00e0 la gestion des d\u00e9bits de ventilation afin de r\u00e9duire les consommations \u00e9lectriques.<\/p>\n<p><strong>Interventions de MATRI<em>ciel<\/em><\/strong><\/p>\n<ul>\n<li>Etudes d\u2019\u00e9clairage artificiel<\/li>\n<li>\u00c9tude \u00e9nerg\u00e9tique et de confort<\/li>\n<li>Mise en place et suivi du concept technique<\/li>\n<li>Etude de la gestion de l\u2019eau<\/li>\n<li>Etude compl\u00e8te des techniques sp\u00e9ciales<\/li>\n<li>Mission de conseiller PEB<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Informations g\u00e9n\u00e9rales Programme :\u00a0Construction d&#8217;une salle de sport en int\u00e9rieur d\u2019\u00eelot Situation :\u00a0Angle Rue Terre Neuve et Rue Roger Van Der Weyden \u00e0 Bruxelles Surface : 2.584\u00a0m2 Ma\u00eetre de l\u2019Ouvrage :\u00a0Ville de Bruxelles Architecte :\u00a0MDW Architecture Dates :\u00a0laur\u00e9at concours en septembre 2016 &#8211; d\u00e9but chantier en f\u00e9vrier 2018 Description du projet Le hall sportif est&hellip;<\/p>\n","protected":false},"author":5,"featured_media":2747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[143],"tags":[135,112,49,71,77],"class_list":["post-2745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-loisirs","tag-confort-thermique","tag-energie-et-confort","tag-gestion-de-leau","tag-peb","tag-techniques-speciales","category-143","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9marrage du chantier de la salle de sport Terre-Neuve \u00e0 Bruxelles<\/title>\n<meta name=\"description\" content=\"MDW Architecture et MATRIciel, associ\u00e9s pour ce chantier de construction de la nouvelle salle de sport &quot;Terre Neuve&quot; pour la Ville de Bruxelles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9marrage du chantier de la salle de sport Terre-Neuve \u00e0 Bruxelles\" \/>\n<meta property=\"og:description\" content=\"MDW Architecture et MATRIciel, associ\u00e9s pour ce chantier de construction de la nouvelle salle de sport &quot;Terre Neuve&quot; pour la Ville de Bruxelles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/\" \/>\n<meta property=\"og:site_name\" content=\"MATRIciel\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-21T08:11:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"catherine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"catherine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/\"},\"author\":{\"name\":\"catherine\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\"},\"headline\":\"Le chantier de la nouvelle salle de sport Terre-Neuve \u00e0 Bruxelles d\u00e9marre !\",\"datePublished\":\"2019-02-21T08:11:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/\"},\"wordCount\":232,\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/1519827667-155-vue-exterieure.jpg\",\"keywords\":[\"Confort thermique\",\"Energie et confort\",\"Gestion de l'eau\",\"PEB\",\"Techniques sp\u00e9ciales\"],\"articleSection\":[\"Culture\\\/Loisirs\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/\",\"name\":\"D\u00e9marrage du chantier de la salle de sport Terre-Neuve \u00e0 Bruxelles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/1519827667-155-vue-exterieure.jpg\",\"datePublished\":\"2019-02-21T08:11:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\"},\"description\":\"MDW Architecture et MATRIciel, associ\u00e9s pour ce chantier de construction de la nouvelle salle de sport \\\"Terre Neuve\\\" pour la Ville de Bruxelles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/1519827667-155-vue-exterieure.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/1519827667-155-vue-exterieure.jpg\",\"width\":800,\"height\":583,\"caption\":\"Le chantier Terre-Neuve d\u00e9marre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.matriciel.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le chantier de la nouvelle salle de sport Terre-Neuve \u00e0 Bruxelles d\u00e9marre !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/\",\"name\":\"MATRIciel\",\"description\":\"Bureau d&#039;\u00e9tude et de conseil en architecture durable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matriciel.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\",\"name\":\"catherine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9marrage du chantier de la salle de sport Terre-Neuve \u00e0 Bruxelles","description":"MDW Architecture et MATRIciel, associ\u00e9s pour ce chantier de construction de la nouvelle salle de sport \"Terre Neuve\" pour la Ville de Bruxelles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/","og_locale":"en_US","og_type":"article","og_title":"D\u00e9marrage du chantier de la salle de sport Terre-Neuve \u00e0 Bruxelles","og_description":"MDW Architecture et MATRIciel, associ\u00e9s pour ce chantier de construction de la nouvelle salle de sport \"Terre Neuve\" pour la Ville de Bruxelles","og_url":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/","og_site_name":"MATRIciel","article_published_time":"2019-02-21T08:11:48+00:00","og_image":[{"width":800,"height":583,"url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg","type":"image\/jpeg"}],"author":"catherine","twitter_card":"summary_large_image","twitter_misc":{"Written by":"catherine","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#article","isPartOf":{"@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/"},"author":{"name":"catherine","@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf"},"headline":"Le chantier de la nouvelle salle de sport Terre-Neuve \u00e0 Bruxelles d\u00e9marre !","datePublished":"2019-02-21T08:11:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/"},"wordCount":232,"image":{"@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg","keywords":["Confort thermique","Energie et confort","Gestion de l'eau","PEB","Techniques sp\u00e9ciales"],"articleSection":["Culture\/Loisirs"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/","url":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/","name":"D\u00e9marrage du chantier de la salle de sport Terre-Neuve \u00e0 Bruxelles","isPartOf":{"@id":"https:\/\/www.matriciel.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#primaryimage"},"image":{"@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg","datePublished":"2019-02-21T08:11:48+00:00","author":{"@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf"},"description":"MDW Architecture et MATRIciel, associ\u00e9s pour ce chantier de construction de la nouvelle salle de sport \"Terre Neuve\" pour la Ville de Bruxelles","breadcrumb":{"@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#primaryimage","url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg","contentUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg","width":800,"height":583,"caption":"Le chantier Terre-Neuve d\u00e9marre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matriciel.be\/le-chantier-de-la-nouvelle-salle-de-sport-terre-neuve-a-bruxelles-demarre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.matriciel.be\/en\/"},{"@type":"ListItem","position":2,"name":"Le chantier de la nouvelle salle de sport Terre-Neuve \u00e0 Bruxelles d\u00e9marre !"}]},{"@type":"WebSite","@id":"https:\/\/www.matriciel.be\/#website","url":"https:\/\/www.matriciel.be\/","name":"MATRIciel","description":"Bureau d&#039;\u00e9tude et de conseil en architecture durable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matriciel.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf","name":"catherine"}]}},"jetpack_featured_media_url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2019\/02\/1519827667-155-vue-exterieure.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8HVJL-Ih","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/posts\/2745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/comments?post=2745"}],"version-history":[{"count":0,"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/posts\/2745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/media\/2747"}],"wp:attachment":[{"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/media?parent=2745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/categories?post=2745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matriciel.be\/en\/wp-json\/wp\/v2\/tags?post=2745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}