{"id":21141,"date":"2024-07-16T16:19:13","date_gmt":"2024-07-16T14:19:13","guid":{"rendered":"https:\/\/www.matriciel.be\/?post_type=dt_portfolio&#038;p=21141"},"modified":"2026-05-19T16:15:14","modified_gmt":"2026-05-19T14:15:14","slug":"montoyer10","status":"publish","type":"dt_portfolio","link":"https:\/\/www.matriciel.be\/nl\/projet\/montoyer10\/","title":{"rendered":"Immeuble de bureaux Rue Montoyer 10 &#8211; Bruxelles"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row margin_top=&#8221;-30px&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1721137991802{margin-bottom: 20px !important;}&#8221; el_class=&#8221;custom-copyright&#8221;]<\/p>\n<p style=\"text-align: right;\">\u00a9 Louis De Waele, Ma\u00eetre d&#8217;ouvrage : Cofinimmo Offices, Architecte : LD2 Architecture<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243; el_class=&#8221;custom-bold-list&#8221;][vc_column_text]<\/p>\n<h2 style=\"font-size: 25px; line-height: 32px; text-transform: none;\">Informations g\u00e9n\u00e9rales du projet<\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<b>Ma\u00eetre de l&#8217;Ouvrage <\/b>: Cofinimmo Offices<\/p>\n<p><b>Programme :<\/b> Immeuble de bureaux<\/p>\n<p><b>Situation\u00a0<\/b>: Rue Montoyer 10 \u00e0 1000 Bruxelles<\/p>\n<p><b>Surface\u00a0<\/b>: 6.255 m\u00b2 (R+7)<\/p>\n<p><b>Architectes <\/b>: LD2 Architecture<\/p>\n<p><b>Entrepreneur g\u00e9n\u00e9ral : <\/b>Louis De Waele<\/p>\n<p><b>Dates <\/b>: PU octroy\u00e9 en juillet 2021 \u2013 R\u00e9ception provisoire en ao\u00fbt 2024[\/vc_column_text][vc_column_text]<\/p>\n<h2 style=\"font-size: 25px; line-height: 32px; text-transform: none;\">Missions de MATRI<em>ciel<\/em><\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<b><\/b>Etudes des techniques sp\u00e9ciales, dossier d\u2019ex\u00e9cution, suivi de chantier, r\u00e9ception et mise en service<br \/>\n<b><\/b>Mission de Conseiller PEB<br \/>\n<b><\/b>Mission d\u2019assesseur BREEAM<br \/>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h2>Description du projet<\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3>D\u00e9molition et reconstruction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, situ\u00e9 rue Montoyer 10 \u00e0 1000 Bruxelles.<\/h3>\n<h4>Performance \u00e9nerg\u00e9tique<\/h4>\n<p>Le projet, par ses qualit\u00e9s de d\u00e9veloppement et ses choix techniques, permet de r\u00e9duire son impact environnemental et sa consommation en \u00e9nergie primaire pour \u00eatre qualifi\u00e9 de &#8220;Nearly Zero Energy Building&#8221; (NZEB).<\/p>\n<p>Le projet a \u00e9t\u00e9 \u00e9tudi\u00e9 pour limiter sa consommation \u00e9nerg\u00e9tique gr\u00e2ce \u00e0 son enveloppe et ses \u00e9quipements techniques performants :<\/p>\n<ul>\n<li>Isolation tr\u00e8s performante (triples vitrages et coefficient de transmission thermique U moyen des parois de 0,14 W\/m\u00b2K) ;<\/li>\n<li>Etanch\u00e9it\u00e9 \u00e0 l\u2019air renforc\u00e9e (0,63 h-1 sous 50 Pa) ;<\/li>\n<li>Parfaite gestion des points d\u2019affaiblissement thermique (n\u0153uds constructifs) ;<\/li>\n<li>Production de chaud\/froid assur\u00e9e par une pompe \u00e0 chaleur r\u00e9versible ;<\/li>\n<li>Production d\u2019\u00e9nergie solaire photovolta\u00efque optimale.<\/li>\n<\/ul>\n<p>Ces choix techniques et architecturaux permettent au b\u00e2timent d&#8217;atteindre une consommation en \u00e9nergie primaire inf\u00e9rieure \u00e0 25 kWh\/m\u00b2 par an.<\/p>\n<h4>Certification environnementale<\/h4>\n<p>Le respect de crit\u00e8res de conception tr\u00e8s \u00e9lev\u00e9s en mati\u00e8re de durabilit\u00e9, tant pour le b\u00e2timent que pour ses installations techniques, a permis d&#8217;obtenir la certification CO2 Neutral &#8220;Silver Building&#8221; et permet de viser une certification BREEAM &#8220;Outstanding&#8221; (certificat interm\u00e9diaire obtenu).<\/p>\n<p>Les \u00e9l\u00e9ments cl\u00e9s permettant cette performance environnementale sont la superstructure majoritairement en bois issu d&#8217;une gestion foresti\u00e8re durable, l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique et l&#8217;absence de combustibles fossiles.<\/p>\n<p>L&#8217;empreinte carbone du b\u00e2timent sur l&#8217;ensemble de son cycle de vie (sur une p\u00e9riode de 60 ans) est ainsi de 0,98 tCO2e\/m\u00b2 pour le carbone embarqu\u00e9 et de 0,01 tCO2e\/m\u00b2 pour le carbone op\u00e9rationnel.<\/p>\n<h4>Confort, sant\u00e9 et bien-\u00eatre<\/h4>\n<p>Gr\u00e2ce \u00e0 sa qualit\u00e9 architecturale et aux choix techniques op\u00e9r\u00e9s, le b\u00e2timent vise \u00e9galement la certification WELL &#8220;Platinium&#8221; (certificat interm\u00e9diaire obtenu).<\/p>\n<h4>Gestion de l\u2019eau<\/h4>\n<ul>\n<li>Equipements sanitaires \u00e9conomes en eau ;<\/li>\n<li>R\u00e9servoir d&#8217;eau de pluie de 32 000 litres et r\u00e9utilisation de l&#8217;eau de pluie pour alimenter tous les WC et les appareils d\u2019entretien de abords.<\/li>\n<\/ul>\n<h4>Techniques sp\u00e9ciales<\/h4>\n<ul>\n<li>PAC 4 tubes d\u00e9livrant du chaud et du froid simultan\u00e9ment par l&#8217;interm\u00e9diaire de plafonds actifs, permettant ainsi la valorisation des performances en entre-saison ;<\/li>\n<li>Distribution 4 tubes par plateau et r\u00e9gulation des \u00e9missions de chaud et de froid par module de fa\u00e7ade par l\u2019action de vannes 6 voies ;<\/li>\n<li>Production d\u2019ECS instantan\u00e9e et localis\u00e9e \u00e0 proximit\u00e9 des \u00e9quipements (douches) pour \u00e9viter les pertes thermiques dans une boucle d&#8217;ECS ;<\/li>\n<li>Groupe de ventilation double flux avec roue \u00e0 r\u00e9cup\u00e9ration de chaleur et d&#8217;humidit\u00e9 ;<\/li>\n<li>Toiture optimis\u00e9e pour le placement de 150 panneaux photovolta\u00efques produisant 20 % des besoins en \u00e9nergie du b\u00e2timent ;<\/li>\n<li>Eclairage artificiel LED \u00e0 haute efficacit\u00e9 \u00e9nerg\u00e9tique avec adaptation de la puissance en fonction des apports en \u00e9clairage naturel<\/li>\n<li>Installation de sprinklage dans le parking et sur les plateaux de bureaux<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><B>Montoyer 10<\/B><br \/>\n<B>MO <\/B>Cofinimmo Offices<br \/>\n<B>Ar <\/B>LD2 architecture<\/p>\n","protected":false},"author":5,"featured_media":21148,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[289,291,10],"dt_portfolio_tags":[283,284,285,241],"class_list":["post-21141","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-certification","dt_portfolio_category-certification-phare","dt_portfolio_category-bureau","dt_portfolio_tags-breeam-outstanding","dt_portfolio_tags-certification-co2-neutral-silver-building","dt_portfolio_tags-certiification-well-platinium","dt_portfolio_tags-nearly-zero-energy-building","dt_portfolio_category-289","dt_portfolio_category-291","dt_portfolio_category-10","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immeuble de bureaux Rue Montoyer 10 - Bruxelles - MATRIciel<\/title>\n<meta name=\"description\" content=\"Etudes TS, PEB, BREEAM et WELL pour la construction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, rue Montoyer 10 \u00e0 BXL\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matriciel.be\/projet\/montoyer10\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immeuble de bureaux Rue Montoyer 10 - Bruxelles - MATRIciel\" \/>\n<meta property=\"og:description\" content=\"Etudes TS, PEB, BREEAM et WELL pour la construction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, rue Montoyer 10 \u00e0 BXL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matriciel.be\/projet\/montoyer10\/\" \/>\n<meta property=\"og:site_name\" content=\"MATRIciel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T14:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matriciel.be\/wp-content\/uploads\/2024\/07\/LDW-Montoyer-1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/\",\"name\":\"Immeuble de bureaux Rue Montoyer 10 - Bruxelles - MATRIciel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/LDW-Montoyer-1080.jpg\",\"datePublished\":\"2024-07-16T14:19:13+00:00\",\"dateModified\":\"2026-05-19T14:15:14+00:00\",\"description\":\"Etudes TS, PEB, BREEAM et WELL pour la construction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, rue Montoyer 10 \u00e0 BXL\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/LDW-Montoyer-1080.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/LDW-Montoyer-1080.jpg\",\"width\":1200,\"height\":928,\"caption\":\"Immeuble de bureaux - Montoyer 10 - BREEAM Outstanding - WELL Platinium - CO2 Neutral Silver Building\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/projet\\\/montoyer10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/projet\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Immeuble de bureaux Rue Montoyer 10 &#8211; Bruxelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/\",\"name\":\"MATRIciel\",\"description\":\"Bureau d&#039;\u00e9tude et de conseil en architecture durable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matriciel.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immeuble de bureaux Rue Montoyer 10 - Bruxelles - MATRIciel","description":"Etudes TS, PEB, BREEAM et WELL pour la construction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, rue Montoyer 10 \u00e0 BXL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matriciel.be\/projet\/montoyer10\/","og_locale":"nl_NL","og_type":"article","og_title":"Immeuble de bureaux Rue Montoyer 10 - Bruxelles - MATRIciel","og_description":"Etudes TS, PEB, BREEAM et WELL pour la construction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, rue Montoyer 10 \u00e0 BXL","og_url":"https:\/\/www.matriciel.be\/projet\/montoyer10\/","og_site_name":"MATRIciel","article_modified_time":"2026-05-19T14:15:14+00:00","og_image":[{"width":1200,"height":928,"url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2024\/07\/LDW-Montoyer-1080.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"3 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.matriciel.be\/projet\/montoyer10\/","url":"https:\/\/www.matriciel.be\/projet\/montoyer10\/","name":"Immeuble de bureaux Rue Montoyer 10 - Bruxelles - MATRIciel","isPartOf":{"@id":"https:\/\/www.matriciel.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matriciel.be\/projet\/montoyer10\/#primaryimage"},"image":{"@id":"https:\/\/www.matriciel.be\/projet\/montoyer10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2024\/07\/LDW-Montoyer-1080.jpg","datePublished":"2024-07-16T14:19:13+00:00","dateModified":"2026-05-19T14:15:14+00:00","description":"Etudes TS, PEB, BREEAM et WELL pour la construction d\u2019un immeuble de bureaux en structure mixte bois et b\u00e9ton, rue Montoyer 10 \u00e0 BXL","breadcrumb":{"@id":"https:\/\/www.matriciel.be\/projet\/montoyer10\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matriciel.be\/projet\/montoyer10\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.matriciel.be\/projet\/montoyer10\/#primaryimage","url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2024\/07\/LDW-Montoyer-1080.jpg","contentUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2024\/07\/LDW-Montoyer-1080.jpg","width":1200,"height":928,"caption":"Immeuble de bureaux - Montoyer 10 - BREEAM Outstanding - WELL Platinium - CO2 Neutral Silver Building"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matriciel.be\/projet\/montoyer10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.matriciel.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.matriciel.be\/nl\/projet\/"},{"@type":"ListItem","position":3,"name":"Immeuble de bureaux Rue Montoyer 10 &#8211; Bruxelles"}]},{"@type":"WebSite","@id":"https:\/\/www.matriciel.be\/#website","url":"https:\/\/www.matriciel.be\/","name":"MATRIciel","description":"Bureau d&#039;\u00e9tude et de conseil en architecture durable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matriciel.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/dt_portfolio\/21141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/comments?post=21141"}],"version-history":[{"count":5,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/dt_portfolio\/21141\/revisions"}],"predecessor-version":[{"id":25393,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/dt_portfolio\/21141\/revisions\/25393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/media\/21148"}],"wp:attachment":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/media?parent=21141"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/dt_portfolio_category?post=21141"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/dt_portfolio_tags?post=21141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}