{"id":2514,"date":"2018-09-17T10:35:59","date_gmt":"2018-09-17T08:35:59","guid":{"rendered":"https:\/\/agencepoush-newmatriciel.pf503.wpserveur.net\/?p=2514"},"modified":"2018-10-04T10:42:24","modified_gmt":"2018-10-04T08:42:24","slug":"news-eau","status":"publish","type":"post","link":"https:\/\/www.matriciel.be\/nl\/news-eau\/","title":{"rendered":"P\u00e9nurie d&#8217;eau &#8230; quelle r\u00e9ponse apporter?"},"content":{"rendered":"<p>La question de l&#8217;eau devient de plus en plus importante \u00e0 prendre en compte dans tout d\u00e9veloppement immobilier.<\/p>\n<p>Il est n\u00e9cessaire de r\u00e9fl\u00e9chir aux questions suivantes :<\/p>\n<ul>\n<li>comment limiter l\u2019impact des constructions et\u00a0des surfaces imperm\u00e9abilis\u00e9es (quartier,\u00a0immeuble et ses abords) sur le\u00a0cycle naturel de l\u2019eau<\/li>\n<li>comment limiter la consommation d\u2019eau pour\u00a0r\u00e9duire le puisage dans les nappes\u00a0phr\u00e9atiques et l\u2019impact environnemental\u00a0du traitement des eaux us\u00e9es<\/li>\n<li>comment assurer le maintien de la qualit\u00e9 des\u00a0eaux par rapport aux sources de pollution<\/li>\n<li>comment g\u00e9rer, par des techniques alternatives, les eaux de pluie et d&#8217;orage \u00e0 l&#8217;\u00e9chelle des \u00eelots et des quartiers, dans une dynamique paysag\u00e8re et de biodiversit\u00e9 (ex : marais filtrants, noues d&#8217;infiltration, stockage, &#8230;).<\/li>\n<\/ul>\n<p>MATRI<em>ciel<\/em>\u00a0est le partenaire id\u00e9al pour r\u00e9pondre \u00e0 ces questions. Contactez-nous pour en discuter !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La question de l&#8217;eau devient de plus en plus importante \u00e0 prendre en compte dans tout d\u00e9veloppement immobilier. Il est n\u00e9cessaire de r\u00e9fl\u00e9chir aux questions suivantes : comment limiter l\u2019impact des constructions et\u00a0des surfaces imperm\u00e9abilis\u00e9es (quartier,\u00a0immeuble et ses abords) sur le\u00a0cycle naturel de l\u2019eau comment limiter la consommation d\u2019eau pour\u00a0r\u00e9duire le puisage dans les nappes\u00a0phr\u00e9atiques&hellip;<\/p>\n","protected":false},"author":5,"featured_media":2516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[132],"tags":[84,104,49,48],"class_list":["post-2514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metier","tag-biodiversite","tag-environnement","tag-gestion-de-leau","tag-quartier-durable","category-132","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confiez les questions de la gestion de l&#039;eau \u00e0 MATRIciel !<\/title>\n<meta name=\"description\" content=\"MATRIciel est le partenaire id\u00e9al pour r\u00e9fl\u00e9chir \u00e0 la question de l&#039;eau dans vos projets de d\u00e9veloppement de quartier durable\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matriciel.be\/nl\/news-eau\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confiez les questions de la gestion de l&#039;eau \u00e0 MATRIciel !\" \/>\n<meta property=\"og:description\" content=\"MATRIciel est le partenaire id\u00e9al pour r\u00e9fl\u00e9chir \u00e0 la question de l&#039;eau dans vos projets de d\u00e9veloppement de quartier durable\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matriciel.be\/nl\/news-eau\/\" \/>\n<meta property=\"og:site_name\" content=\"MATRIciel\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-17T08:35:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-04T08:42:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2116\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"catherine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"catherine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/\"},\"author\":{\"name\":\"catherine\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\"},\"headline\":\"P\u00e9nurie d&#8217;eau &#8230; quelle r\u00e9ponse apporter?\",\"datePublished\":\"2018-09-17T08:35:59+00:00\",\"dateModified\":\"2018-10-04T08:42:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/\"},\"wordCount\":154,\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/iStock-510386918-s\u00e9cheresse.jpg\",\"keywords\":[\"Biodiversit\u00e9\",\"Environnement\",\"Gestion de l'eau\",\"Quartier durable\"],\"articleSection\":[\"M\u00e9tier\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/\",\"name\":\"Confiez les questions de la gestion de l'eau \u00e0 MATRIciel !\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/iStock-510386918-s\u00e9cheresse.jpg\",\"datePublished\":\"2018-09-17T08:35:59+00:00\",\"dateModified\":\"2018-10-04T08:42:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\"},\"description\":\"MATRIciel est le partenaire id\u00e9al pour r\u00e9fl\u00e9chir \u00e0 la question de l'eau dans vos projets de d\u00e9veloppement de quartier durable\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/iStock-510386918-s\u00e9cheresse.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/iStock-510386918-s\u00e9cheresse.jpg\",\"width\":2116,\"height\":1417,\"caption\":\"Faire face \u00e0 la p\u00e9nurie d'eau\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/news-eau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00e9nurie d&#8217;eau &#8230; quelle r\u00e9ponse apporter?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/\",\"name\":\"MATRIciel\",\"description\":\"Bureau d&#039;\u00e9tude et de conseil en architecture durable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matriciel.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\",\"name\":\"catherine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confiez les questions de la gestion de l'eau \u00e0 MATRIciel !","description":"MATRIciel est le partenaire id\u00e9al pour r\u00e9fl\u00e9chir \u00e0 la question de l'eau dans vos projets de d\u00e9veloppement de quartier durable","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matriciel.be\/nl\/news-eau\/","og_locale":"nl_NL","og_type":"article","og_title":"Confiez les questions de la gestion de l'eau \u00e0 MATRIciel !","og_description":"MATRIciel est le partenaire id\u00e9al pour r\u00e9fl\u00e9chir \u00e0 la question de l'eau dans vos projets de d\u00e9veloppement de quartier durable","og_url":"https:\/\/www.matriciel.be\/nl\/news-eau\/","og_site_name":"MATRIciel","article_published_time":"2018-09-17T08:35:59+00:00","article_modified_time":"2018-10-04T08:42:24+00:00","og_image":[{"width":2116,"height":1417,"url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg","type":"image\/jpeg"}],"author":"catherine","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"catherine","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#article","isPartOf":{"@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/"},"author":{"name":"catherine","@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf"},"headline":"P\u00e9nurie d&#8217;eau &#8230; quelle r\u00e9ponse apporter?","datePublished":"2018-09-17T08:35:59+00:00","dateModified":"2018-10-04T08:42:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/"},"wordCount":154,"image":{"@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg","keywords":["Biodiversit\u00e9","Environnement","Gestion de l'eau","Quartier durable"],"articleSection":["M\u00e9tier"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/","url":"https:\/\/www.matriciel.be\/nl\/news-eau\/","name":"Confiez les questions de la gestion de l'eau \u00e0 MATRIciel !","isPartOf":{"@id":"https:\/\/www.matriciel.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#primaryimage"},"image":{"@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg","datePublished":"2018-09-17T08:35:59+00:00","dateModified":"2018-10-04T08:42:24+00:00","author":{"@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf"},"description":"MATRIciel est le partenaire id\u00e9al pour r\u00e9fl\u00e9chir \u00e0 la question de l'eau dans vos projets de d\u00e9veloppement de quartier durable","breadcrumb":{"@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matriciel.be\/nl\/news-eau\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#primaryimage","url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg","contentUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg","width":2116,"height":1417,"caption":"Faire face \u00e0 la p\u00e9nurie d'eau"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matriciel.be\/nl\/news-eau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.matriciel.be\/nl\/"},{"@type":"ListItem","position":2,"name":"P\u00e9nurie d&#8217;eau &#8230; quelle r\u00e9ponse apporter?"}]},{"@type":"WebSite","@id":"https:\/\/www.matriciel.be\/#website","url":"https:\/\/www.matriciel.be\/","name":"MATRIciel","description":"Bureau d&#039;\u00e9tude et de conseil en architecture durable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matriciel.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf","name":"catherine"}]}},"jetpack_featured_media_url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2018\/10\/iStock-510386918-s\u00e9cheresse.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8HVJL-Ey","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/posts\/2514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/comments?post=2514"}],"version-history":[{"count":0,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/posts\/2514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/media?parent=2514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/categories?post=2514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/tags?post=2514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}