{"id":922,"date":"2019-05-20T16:16:21","date_gmt":"2019-05-20T14:16:21","guid":{"rendered":"https:\/\/agencepoush-newmatriciel.pf503.wpserveur.net\/?p=922"},"modified":"2019-05-21T14:06:29","modified_gmt":"2019-05-21T12:06:29","slug":"zinneke","status":"publish","type":"post","link":"https:\/\/www.matriciel.be\/nl\/zinneke\/","title":{"rendered":"R\u00e9novation en &#8220;cradle to cradle&#8221; de l&#8217;ensemble des b\u00e2timents de l&#8217;asbl &#8220;Zinneke&#8221;"},"content":{"rendered":"<h2><strong>R\u00e9novation en &#8220;cradle to cradle&#8221; de l&#8217;ensemble des b\u00e2timents de l&#8217;asbl &#8220;Zinneke&#8221;<\/strong><\/h2>\n<p><!--more--><\/p>\n<p>MATRIciel collabore avec le bureau OUEST Architecture, l\u2019\u00e9quipe de coordination Zinneke et l&#8217;asbl Rotor \u00e0 la r\u00e9novation de l\u2019 \u201cAtelier G\u00e9n\u00e9ral du Timbre\u201d dans le quartier Masui pour y accueillir les activit\u00e9s de l&#8217;asbl &#8220;Zinneke&#8221;.<\/p>\n<p><strong>Informations g\u00e9n\u00e9rales<\/strong><\/p>\n<p><strong>Programme : <\/strong>cinq b\u00e2timents r\u00e9am\u00e9nag\u00e9s pour offrir bureaux, cuisine et cantine, espaces de r\u00e9union et de rencontre, lieux de stockage et archivage, ateliers de production et de formation (m\u00e9tal, bois, costumes, chars, &#8230;) et espaces ext\u00e9rieurs.<br \/>\n<strong>Situation : <\/strong>Place Masui et\u00a0Rue des Palais \u00e0 Bruxelles<br \/>\n<strong>Surface utile : <\/strong>2.300\u00a0m<sup>2<\/sup><br \/>\n<strong>Ma\u00eetre de l&#8217;Ouvrage : <\/strong>Zinneke asbl<br \/>\n<strong>Architecte<\/strong> :\u00a0Ouest Architecture<br \/>\n<strong>Dates :\u00a0<\/strong>d\u00e9marrage des \u00e9tudes en juillet 2016 et du chantier en mars 2019<\/p>\n<p><strong>Description du projet<\/strong><\/p>\n<p>Le projet de r\u00e9habilitation fonctionnelle, technique et \u00e9nerg\u00e9tique du site se veut exemplaire en termes de r\u00e9emploi de mat\u00e9riaux et d\u2019\u00e9quipements.<\/p>\n<p>D\u2019importants d\u00e9fis sont relev\u00e9s en ce sens au niveau du design, des aspects l\u00e9gaux (notamment dans le cadre des march\u00e9s publics), de la collaboration avec les entreprises ou encore des performances \u00e9nerg\u00e9tiques et environnementales.<\/p>\n<p>Par exemple, ce 20 mai 2019, un groupe de ventilation double flux de moins de 5 ans a \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9 suite \u00e0 la d\u00e9molition programm\u00e9e d\u2019un important immeuble bruxellois. Ce groupe performant permettra de ventiler une grande partie des bureaux et des salles polyvalentes.<\/p>\n<p><strong>Interventions de MATRI<em>ciel<br \/>\n<\/em><\/strong><\/p>\n<ul>\n<li>Guidance \u00e9nerg\u00e9tique et environnementale<\/li>\n<li>Etude des techniques sp\u00e9ciales<\/li>\n<li>Mission de Conseiller PEB<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9novation &#8220;cradle to cradle&#8221; des b\u00e2timents mis \u00e0 disposition de l&#8217;asbl &#8220;Zinneke&#8221;<\/p>\n","protected":false},"author":5,"featured_media":2907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[50],"tags":[80,48,63],"class_list":["post-922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bureaux","tag-cradle-to-cradle","tag-quartier-durable","tag-rehabilitation","category-50","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9novation &quot;cradle to cradle&quot; des nouveaux bureaux de l&#039;asbl Zinneke<\/title>\n<meta name=\"description\" content=\"MATRIciel, Ouest architecture et l&#039;asbl Zinneke, partenaires dans la r\u00e9habilitation &quot;cradle to cradle&quot; des nouveaux espaces de l&#039;asbl.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matriciel.be\/zinneke\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9novation &quot;cradle to cradle&quot; des nouveaux bureaux de l&#039;asbl Zinneke\" \/>\n<meta property=\"og:description\" content=\"MATRIciel, Ouest architecture et l&#039;asbl Zinneke, partenaires dans la r\u00e9habilitation &quot;cradle to cradle&quot; des nouveaux espaces de l&#039;asbl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matriciel.be\/zinneke\/\" \/>\n<meta property=\"og:site_name\" content=\"MATRIciel\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-20T14:16:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-21T12:06:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"643\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"catherine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"catherine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/\"},\"author\":{\"name\":\"catherine\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\"},\"headline\":\"R\u00e9novation en &#8220;cradle to cradle&#8221; de l&#8217;ensemble des b\u00e2timents de l&#8217;asbl &#8220;Zinneke&#8221;\",\"datePublished\":\"2019-05-20T14:16:21+00:00\",\"dateModified\":\"2019-05-21T12:06:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/\"},\"wordCount\":282,\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Photo-Sandrine-1.jpg\",\"keywords\":[\"Cradle to cradle\",\"Quartier durable\",\"R\u00e9habilitation\"],\"articleSection\":[\"Bureaux\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/\",\"name\":\"R\u00e9novation \\\"cradle to cradle\\\" des nouveaux bureaux de l'asbl Zinneke\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Photo-Sandrine-1.jpg\",\"datePublished\":\"2019-05-20T14:16:21+00:00\",\"dateModified\":\"2019-05-21T12:06:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\"},\"description\":\"MATRIciel, Ouest architecture et l'asbl Zinneke, partenaires dans la r\u00e9habilitation \\\"cradle to cradle\\\" des nouveaux espaces de l'asbl.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Photo-Sandrine-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matriciel.be\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Photo-Sandrine-1.jpg\",\"width\":643,\"height\":867,\"caption\":\"R\u00e9cup\u00e9ration d'un groupe de ventilation d'un chantier de d\u00e9molition, pour la r\u00e9novation de l'asbl Zinneke\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/zinneke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.matriciel.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9novation en \u00ab\u00a0cradle to cradle\u00a0\u00bb de l&rsquo;ensemble des b\u00e2timents de l&rsquo;asbl \u00ab\u00a0Zinneke\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#website\",\"url\":\"https:\\\/\\\/www.matriciel.be\\\/\",\"name\":\"MATRIciel\",\"description\":\"Bureau d&#039;\u00e9tude et de conseil en architecture durable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matriciel.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.matriciel.be\\\/#\\\/schema\\\/person\\\/44a6df2b7f4b9aa38fd89d2a2e3036bf\",\"name\":\"catherine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9novation \"cradle to cradle\" des nouveaux bureaux de l'asbl Zinneke","description":"MATRIciel, Ouest architecture et l'asbl Zinneke, partenaires dans la r\u00e9habilitation \"cradle to cradle\" des nouveaux espaces de l'asbl.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matriciel.be\/zinneke\/","og_locale":"nl_NL","og_type":"article","og_title":"R\u00e9novation \"cradle to cradle\" des nouveaux bureaux de l'asbl Zinneke","og_description":"MATRIciel, Ouest architecture et l'asbl Zinneke, partenaires dans la r\u00e9habilitation \"cradle to cradle\" des nouveaux espaces de l'asbl.","og_url":"https:\/\/www.matriciel.be\/zinneke\/","og_site_name":"MATRIciel","article_published_time":"2019-05-20T14:16:21+00:00","article_modified_time":"2019-05-21T12:06:29+00:00","og_image":[{"width":643,"height":867,"url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg","type":"image\/jpeg"}],"author":"catherine","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"catherine","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matriciel.be\/zinneke\/#article","isPartOf":{"@id":"https:\/\/www.matriciel.be\/zinneke\/"},"author":{"name":"catherine","@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf"},"headline":"R\u00e9novation en &#8220;cradle to cradle&#8221; de l&#8217;ensemble des b\u00e2timents de l&#8217;asbl &#8220;Zinneke&#8221;","datePublished":"2019-05-20T14:16:21+00:00","dateModified":"2019-05-21T12:06:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matriciel.be\/zinneke\/"},"wordCount":282,"image":{"@id":"https:\/\/www.matriciel.be\/zinneke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg","keywords":["Cradle to cradle","Quartier durable","R\u00e9habilitation"],"articleSection":["Bureaux"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/www.matriciel.be\/zinneke\/","url":"https:\/\/www.matriciel.be\/zinneke\/","name":"R\u00e9novation \"cradle to cradle\" des nouveaux bureaux de l'asbl Zinneke","isPartOf":{"@id":"https:\/\/www.matriciel.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matriciel.be\/zinneke\/#primaryimage"},"image":{"@id":"https:\/\/www.matriciel.be\/zinneke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg","datePublished":"2019-05-20T14:16:21+00:00","dateModified":"2019-05-21T12:06:29+00:00","author":{"@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf"},"description":"MATRIciel, Ouest architecture et l'asbl Zinneke, partenaires dans la r\u00e9habilitation \"cradle to cradle\" des nouveaux espaces de l'asbl.","breadcrumb":{"@id":"https:\/\/www.matriciel.be\/zinneke\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matriciel.be\/zinneke\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.matriciel.be\/zinneke\/#primaryimage","url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg","contentUrl":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg","width":643,"height":867,"caption":"R\u00e9cup\u00e9ration d'un groupe de ventilation d'un chantier de d\u00e9molition, pour la r\u00e9novation de l'asbl Zinneke"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matriciel.be\/zinneke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.matriciel.be\/nl\/"},{"@type":"ListItem","position":2,"name":"R\u00e9novation en \u00ab\u00a0cradle to cradle\u00a0\u00bb de l&rsquo;ensemble des b\u00e2timents de l&rsquo;asbl \u00ab\u00a0Zinneke\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.matriciel.be\/#website","url":"https:\/\/www.matriciel.be\/","name":"MATRIciel","description":"Bureau d&#039;\u00e9tude et de conseil en architecture durable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matriciel.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/www.matriciel.be\/#\/schema\/person\/44a6df2b7f4b9aa38fd89d2a2e3036bf","name":"catherine"}]}},"jetpack_featured_media_url":"https:\/\/www.matriciel.be\/wp-content\/uploads\/2016\/07\/Photo-Sandrine-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/s8HVJL-zinneke","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/posts\/922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/comments?post=922"}],"version-history":[{"count":0,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/posts\/922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/media\/2907"}],"wp:attachment":[{"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/media?parent=922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/categories?post=922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matriciel.be\/nl\/wp-json\/wp\/v2\/tags?post=922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}